{"id":7500,"date":"2026-07-07T18:42:12","date_gmt":"2026-07-07T17:42:12","guid":{"rendered":"https:\/\/recreacionhistoria.com\/?p=7500"},"modified":"2026-07-07T18:42:12","modified_gmt":"2026-07-07T17:42:12","slug":"o-mar-na-antiga-roma","status":"publish","type":"post","link":"https:\/\/recreacionhistoria.com\/gl\/o-mar-na-antiga-roma\/","title":{"rendered":"O mar na antiga Roma"},"content":{"rendered":"<p>Roma, berce dunha das grandes civilizaci\u00f3ns, fundouse nun lugar no que hab\u00eda outeiros e que facilitaba o seu defensa, ademais de que a trav\u00e9s do r\u00edo T\u00edber, pod\u00eda comunicarse co mar. Segundo a tradici\u00f3n Roma fundouse no ano 753 aC. por R\u00f3mulo e Remo; primeiro foi unha monarqu\u00eda etrusca, daquela (509 aC.) unha Rep\u00fablica e en 27 aC. converteuse nun Imperio.<\/p>\n<p>A pesar da escasa distancia que lle separa do mar e de tratarse dun pobo no que predominaba a s\u00faa forte presenza e ex\u00e9rcito terrestre no seu proceso de desenvolvemento e expansi\u00f3n, tam\u00e9n tiveron unha ampla actividade en torno ao mar, especialmente merc\u00e9 a unha ampla frota, que a\u00ednda que non melloraba as frotas xa existentes no Mediterr\u00e1neo (fenicias, gregas e cartaxinesas, sobre todo), tiveron un papel de relativa relevancia.<\/p>\n<p>Lembremos que os l\u00edmites de Roma, na antig\u00fcidade, eran: polo norte cos Alpes; polo sur co Mar J\u00f3nico e o Mar mediterr\u00e1neo; polo leste co Mar Adri\u00e1tico e polo oeste co Mar Tirreno.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-7202 aligncenter\" src=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/MapaElmarenlaantiguaRoma-300x181.png\" alt=\"\" width=\"300\" height=\"181\" title=\"\" srcset=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/MapaElmarenlaantiguaRoma-300x181.png 300w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/MapaElmarenlaantiguaRoma-1024x619.png 1024w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/MapaElmarenlaantiguaRoma-768x464.png 768w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/MapaElmarenlaantiguaRoma.png 1306w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Durante s\u00e9culos os romanos dominaron o Mediterr\u00e1neo ao que chamaron Mare Nostrum (mar noso).<\/p>\n<p>En torno ao 44 aC. Roma controlaba todo o mundo Mediterr\u00e1neo, ben directamente, ben a trav\u00e9s do control exercido sobre os xefes nativos, convertidos en reis vasalos de Roma.<\/p>\n<p>Os romanos comerciaban primeiramente por terra, constru\u00edron bos cami\u00f1os aos que lle chamaron calzadas romanas para transportar as s\u00faas mercader\u00edas con outros pobos da rexi\u00f3n. Se desexades maior informaci\u00f3n sobre as v\u00edas romanas, podedes consultar o noso post: <a href=\"https:\/\/recreacionhistoria.com\/vias-romanas-pegadas-dunha-enxeneria-perdida\/?lang=gl\">V\u00edas romanas. Pegadas dunha enxe\u00f1ar\u00eda perdida<\/a>.<\/p>\n<p>Para que ese comercio inmenso funcionase, Roma tivo que constru\u00edr portos, rompeolas, almac\u00e9ns, diques secos, faros etc. Con todo, a tradici\u00f3n de construci\u00f3n naval romana v\u00e9n doutras culturas mediterr\u00e1neas, tales como a fenicia, grega e a cartaxinesa.<\/p>\n<p>A navegaci\u00f3n no Mar Mediterr\u00e1neo era perigosa principalmente por mor dos piratas, pero tam\u00e9n debido ao clima rigoroso, os mapas pobres ou as embarcaci\u00f3ns deficientes. Coa chegada de Augusto e a <em>Pax Romana<\/em>, a armada fortaleceuse e os piratas foron literalmente eliminados, as\u00ed o comercio floreceu e moitos portos creceron.<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-7216 alignright\" src=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Navegacionromana-300x150.png\" alt=\"\" width=\"300\" height=\"150\" title=\"\" srcset=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Navegacionromana-300x150.png 300w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Navegacionromana-768x384.png 768w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Navegacionromana.png 797w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Conv\u00e9n tam\u00e9n falar do <strong><em>porto de Ostia<\/em><\/strong>, o m\u00e1is importante do mundo romano. A 30 km. ao oeste de Roma at\u00f3panse as ru\u00ednas da antiga cidade romana de Ostia. A\u00ednda que na actualidade at\u00f3pase a 3 km. da costa, na Antig\u00fcedad, Ostia ach\u00e1base na desembocadura do Tiber. Segundo a tradici\u00f3n, Ostia foi fundada polo cuarto rei de Roma, Anco Marcio, no s\u00e9culo VII aC. A finais do s\u00e9culo IV aC. constru\u00eduse un<em> castrum<\/em>, un recinto militar. Este centro militar ocupou un importante papel no control dos piratas no Mediterr\u00e1neo e no desenvolvemento das guerras p\u00fanicas entre Roma e Cartago. A partir do s\u00e9culo II aC., o papel militar pasou a un segundo plano, emerxendo a Ostia comercial, onde se almacenaba o gran importado de Sicilia, Sarde\u00f1a e \u00c1frica. A consideraci\u00f3n de porto de Ostia como o m\u00e1is importante do Imperio veu dada primeiro polo emperador Claudio, e posteriormente por Trajano e a dinast\u00eda severa. Claudio ordenou a construci\u00f3n dun porto artificial, Portus, ao norte da cidade, no 42 dC., que permitiu a protecci\u00f3n dos grandes barcos. A d\u00e1rsena escavada estaba protexida por dous espig\u00f3ns que salvagardaban \u00e1s naves al\u00ed amarradas. D\u00e9cadas despois, o emperador Trajano mellorou as obras do porto con a construci\u00f3n dunha segunda d\u00e1rsena, entre os anos 106-113 dC. Por aqu\u00ed entraba o gran de Exipto, alimento fundamental para a manutenci\u00f3n do pobo romano.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_7200\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-7200\" class=\"wp-image-7200 size-medium\" src=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/OstiaElGranPuertodeRoma-300x210.jpg\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/OstiaElGranPuertodeRoma-300x210.jpg 300w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/OstiaElGranPuertodeRoma-768x538.jpg 768w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/OstiaElGranPuertodeRoma.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-7200\" class=\"wp-caption-text\"><em>Ostia, o gran porto de Roma<\/em><\/p><\/div>\n<p>O Mediterr\u00e1neo foi ademais unha <strong><em>ruta comercial de gran importancia<\/em><\/strong>. O Mediterr\u00e1neo, o Mare Nostrum era un mar dominado case exclusivamente por Roma, o que sen d\u00fabida lle dotaba de maior seguridade como v\u00eda de transporte de mercador\u00edas. O comercio mar\u00edtimo era moito m\u00e1is r\u00e1pido que o terrestre e o valor das mercador\u00edas adoitaba ser moito m\u00e1is valioso; exemplos diso t\u00e9molo na Pen\u00ednsula Ib\u00e9rica de onde provi\u00f1a o aceite de oliva, o vi\u00f1o e os metais (da B\u00e9tica) e desde o outro lado do Imperio, tam\u00e9n desde o mar, tanto desde Constantinopla, como desde a costa Siro-palestina, as especias, a seda e produtos orientais (ruta da seda). Estes elementos eran tra\u00eddos a Roma para fornecerllos \u00e1 aristocracia e ao sector relixioso en primeiro lugar. E de calidades inferiores (vi\u00f1o e aceite) para o resto da poboaci\u00f3n. No entanto, tam\u00e9n se enviaban \u00e1 capital cereais desde Exipto e \u00c1frica, pois eran os celeiros do Imperio.<\/p>\n<p>Os barcos pertenc\u00edan xeralmente a persoas particulares que ademais eran donos dos peiraos e os almac\u00e9ns portuarios. A\u00ednda que s\u00f3 cubr\u00edan uns 60 quil\u00f3metros por d\u00eda, eran naves bastante r\u00e1pidas, algo necesario debido ao perigo que representaban os piratas. Por iso, en ocasi\u00f3ns, o comerciante v\u00edase obrigado a contratar protecci\u00f3n para salvagardar a s\u00faa valiosa carga.<\/p>\n<p>O principal medio de pago no comercio romano eran as moedas que pod\u00edan ser de ouro (<em>aureus<\/em>), de prata (<em>denarius<\/em>), de bronce <em>(sestersius<\/em>) ou de cobre (<em>dupondius<\/em>). As moedas romanas ti\u00f1an valor por si mesmas, xa que estaban feitas de metais valiosos e non necesitaban de ning\u00fan respaldo.<\/p>\n<p><strong><em> <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7208 alignleft\" src=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/ElmarenlaAntiguaRoma-300x130.jpg\" alt=\"\" width=\"300\" height=\"130\" title=\"\" srcset=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/ElmarenlaAntiguaRoma-300x130.jpg 300w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/ElmarenlaAntiguaRoma.jpg 736w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>En canto ao tipo de barcos<\/em><\/strong> que utilizaban hai que dicir que eran moi diferentes entre eles, atendendo sobre todo \u00e1 s\u00faa funci\u00f3n, segundo foses barcos de guerra, de pesca ou para o comercio mar\u00edtimo. Ademais tam\u00e9n influ\u00eda se eran barcos destinados a navegar por mar, por r\u00edo ou en lagos.<\/p>\n<p>&nbsp;<\/p>\n<p>Con algunhas excepci\u00f3ns, \u00e9 sabido que as naves romanas raramente exced\u00edan unha eslora de corenta metros.<\/p>\n<p>&nbsp;<\/p>\n<p>As grandes direcci\u00f3ns do comercio mar\u00edtimo no mediterr\u00e1neo foron, durante o imperio romano, do leste ao oeste e rec\u00edprocamente, e desde os diversos puntos da periferia cara ao centro, \u00e9 dicir, cara aos principais portos da pen\u00ednsula it\u00e1lica. En oriente, as cabezas de li\u00f1a m\u00e1is importantes da navegaci\u00f3n comercial eran, de norte a sur. No litoral do \u00c1frica do norte, o gran comercio estaba concentrado nos portos de Tripolitania, sobre todo en Leptis magna, onde desembocaban as principais rutas das caravanas que atravesaban o Sahara, e en Cartago, reconstru\u00eddo por Cesar e por Augusto. Na Europa occidental, Gades en Espa\u00f1a, Narbona e Arles na Galia manti\u00f1an relaci\u00f3ns regulares e frecuentes xa co oriente, xa con Italia.<\/p>\n<div id=\"attachment_7214\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7214\" class=\"wp-image-7214 size-medium\" src=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/BarcoTransporteRomano-300x240.gif\" alt=\"\" width=\"300\" height=\"240\" title=\"\"><p id=\"caption-attachment-7214\" class=\"wp-caption-text\"><em>Barco de transporte romano<\/em><\/p><\/div>\n<p>En todas as rutas a circulaci\u00f3n non era completamente libre. As mercador\u00edas, transportadas a trav\u00e9s do imperio, ti\u00f1an que pagar m\u00faltiples dereitos cuxo conxunto formaba o que se chamaba o <em>portorium,<\/em> consistente en tres clases de impostos ou de taxas co\u00f1ecidos polos modernos; a aduana, o arbitrio, a peaxe.<\/p>\n<p>Os barcos mar\u00edtimos romanos ad\u00f3itaselles chamar <em>naves onerariae<\/em>. Variaban por tipo de barco, veas e maquinarias. Elementos com\u00fans entre elas eran o sistema de conduci\u00f3n caracterizado por un tem\u00f3n e dous remos laterais (para poder ser manobrada por unha soa persoa) a cabina de popa e a lona cadra perpendicular ao eixo da embarcaci\u00f3n. O sistema de propulsi\u00f3n xeralmente era a trav\u00e9s de lonas e raramente present\u00e1base un sistema mixto de lona m\u00e1is remos.<\/p>\n<p>&nbsp;<\/p>\n<p>Podemos dicir que <strong><em>segundo a forma do casco dos barcos mercantes<\/em><\/strong> romanos haber\u00eda tres tipos:<\/p>\n<ul>\n<li>Os de proa convexa e popa redondeada<\/li>\n<li>Os que ti\u00f1an proa e popa sim\u00e9trica, os menos frecuentes<\/li>\n<li>Os de proa c\u00f3ncava, en forma de espor\u00f3n e unha popa similar \u00e1s anteriores<\/li>\n<\/ul>\n<p>A forma da popa aproveit\u00e1base para instalar os habit\u00e1culos e para engadir elementos decorativos, como o pescozo de cisne que remataba o codaste. A proa e as velas eran tam\u00e9n decoradas con divindades protectoras ou escenas mitol\u00f3xicas.<\/p>\n<p>A capacidade media de carga dos nav\u00edos mercantes oscilaba, dependendo das s\u00faas dimensi\u00f3ns, entre 3.000 e as 5.000 \u00e1nforas de 26 litros de produto, m\u00e1is 17 ou 18 quilos de peso do envase. Isto sup\u00f3n unhas 130 a 200 toneladas de carga, \u00e1s que haber\u00eda que sumar o peso da embarcaci\u00f3n para co\u00f1ecer o desprazamento.<\/p>\n<p>A velocidade destes nav\u00edos que se desprazaban polo mediterr\u00e1neo, en condici\u00f3ns de vento favorable, pod\u00eda alcanzar o seis n\u00f3s, percorrendo, segundo as fontes escritas, 935 millas n\u00e1uticas, distancia existente entre Xibraltar e o porto de Ostia, en sete d\u00edas.<\/p>\n<p>O sistema de goberno destes barcos consist\u00eda en dous enormes remos situados na popa. Estes tem\u00f3ns accion\u00e1banse por medio dunha cana, conseguindo, cun s\u00f3 home, o rumbo desexado. O velamen destas naves era xeralmente unha vela cadra arboredo nun \u00fanico mastro.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_7204\" style=\"width: 310px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7204\" class=\"wp-image-7204 size-medium\" src=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Guerrasp\u00fanicasRomaVSCartago-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" title=\"\" srcset=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Guerrasp\u00fanicasRomaVSCartago-300x200.jpg 300w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Guerrasp\u00fanicasRomaVSCartago.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-7204\" class=\"wp-caption-text\"><em>Roma vs Cartago. Guerras p\u00fanicas<\/em><\/p><\/div>\n<p><strong><em>Para referirnos \u00e1 forza naval<\/em><\/strong>, lembremos que os romanos na s\u00faa orixe eran unha potencia terrestre, pero no mar eran d\u00e9biles, dado que durante as guerras P\u00fanicas a maior parte dos combates tiveron lugar en ultramar. Con motivo da primeira guerra p\u00fanica (264-241 aC.), que lle enfrontou cos cartaxineses, por primeira vez Roma tivo que constru\u00edr unha forza naval, orixe do seu dominio do Mediterr\u00e1neo occidental, composta por 150 quinquerremes e trirremes que operaban no Estreito de Messina, entre Sicilia e Calabria. Con posterioridade, a vista volveuse cara ao Mediterr\u00e1neo oriental derrotando sucesivamente a Macedonios e Sirios, entre os anos 197 e 190 aC.<\/p>\n<p>&nbsp;<\/p>\n<p>A mari\u00f1a romana ti\u00f1a d\u00faas bases importantes, as\u00ed como varias de menor categor\u00eda. As d\u00faas <strong><em>frotas principais que controlaban o Mare Nostrum <\/em><\/strong>foron:<\/p>\n<ul>\n<li><strong><em>Classis Misenensis<\/em><\/strong>. Era a base naval m\u00e1is grande da armada romana. Controlaba a parte oriental do Mar Mediterr\u00e1neo. No ano 330, as naves despraz\u00e1ronse a Constantinopla, nova capital do Imperio Romano.<\/li>\n<li><strong><em>Classis Ravennatis<\/em><\/strong>. Con base en R\u00e1vena desde o ano 27 aC., foi utilizada para controlar a parte occidental do Mar Mediterr\u00e1neo. No ano 330 as naves traslad\u00e1ronse a Constantinopla.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>En canto <strong><em>\u00e1 organizaci\u00f3n da frota<\/em><\/strong>, temos que falar de:<\/p>\n<ul>\n<li><em>Un xefe das tropas<\/em> <em>e da frota<\/em><\/li>\n<li>O prefecto da frota, <em>praefectus classis<\/em><\/li>\n<li>En ocasi\u00f3ns elix\u00edanse dous maxistrados, <em>duoviri navais<\/em>, nos comicios tribais, <em>comitia tributa<\/em>, pero ign\u00f3rase a s\u00faa funci\u00f3n na mari\u00f1a<\/li>\n<li>Un capit\u00e1n, <em>magister navis<\/em>, en cada nav\u00edo<\/li>\n<li>Un piloto, <em>gubernator <\/em><\/li>\n<li><em>Decuriones<\/em> que organizaban o equipamento da nave.<\/li>\n<li>Nos portos militares como Ostia, preto de Roma, hab\u00eda maxistrados encargados de administralos, os questores da frota: <em>quaestores classici<\/em><\/li>\n<li>Cada nave estaba equipada con remeiros, <em>remiges<\/em>, que eran escravos<\/li>\n<li>Tam\u00e9n mari\u00f1eiros, nautae, que Roma recrutaba entre os proletarios, libertos ou aliados mar\u00edtimos (estes \u00faltimos chamados <em>socii navais<\/em> e aos que Roma non dubidaba en confiar os seus barcos)<\/li>\n<li>Soldados de infantar\u00eda de mari\u00f1a, <em>classiarii<\/em>, que fac\u00edan os combates nas cubertas dos barcos e que pod\u00edan ser estranxeiros e libertos, e mesmo en ocasi\u00f3ns escravos<\/li>\n<\/ul>\n<div id=\"attachment_7206\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7206\" class=\"wp-image-7206 size-medium\" src=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Reconstrucci\u00f3nBirreme-300x195.jpg\" alt=\"\" width=\"300\" height=\"195\" title=\"\" srcset=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Reconstrucci\u00f3nBirreme-300x195.jpg 300w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Reconstrucci\u00f3nBirreme.jpg 425w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-7206\" class=\"wp-caption-text\"><em>Reconstrucci\u00f3n Birreme<\/em><\/p><\/div>\n<p>&nbsp;<\/p>\n<p>As naves de guerra en xeral reciben o nome de <em>naves longae<\/em> (naves longas) en oposici\u00f3n \u00e1s naves comerciais m\u00e1is redonda e con menos eslora, pero m\u00e1is pesadas (<em>as oneraria naves<\/em>).\u00a0 A\u00ednda que todos os barcos contaban con velas, a forza motriz tam\u00e9n se baseaba nos remeiros.<\/p>\n<p>&nbsp;<\/p>\n<p>En funci\u00f3n do n\u00famero de remeiros, as naves recib\u00edan o nome de: <em>biremis, triremis, quadremis ou quinqueremis<\/em> segundo tivesen dous, tres, catro ou cinco filas de remeiros por lado. As triremis e as quinqueremis eran as m\u00e1is frecuentes.\u00a0 Son barcos de pouco calado, \u00e9 dicir, apenas hai parte do barco por baixo da auga, con pouca tonelaxe.\u00a0 Un quinqueremis contaba con 300 remiges, 120 classiarii e un n\u00famero indeterminado de nautae.<\/p>\n<p>&nbsp;<\/p>\n<p>Con Octavio Augusto e o imperio creouse unha frota permanente, nun principio como polic\u00eda naval para protexer os nav\u00edos de abastecemento dos piratas, xa que o Mediterr\u00e1neo estaba pacificado.\u00a0 A frota imperial divid\u00edase en 8 escuadras e 3 flotillas.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_7212\" style=\"width: 310px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7212\" class=\"wp-image-7212 size-medium\" src=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Salinasromanas-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" title=\"\" srcset=\"https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Salinasromanas-300x200.jpg 300w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Salinasromanas-1024x681.jpg 1024w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Salinasromanas-768x511.jpg 768w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Salinasromanas-1536x1021.jpg 1536w, https:\/\/recreacionhistoria.com\/wp-content\/uploads\/2020\/08\/Salinasromanas.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-7212\" class=\"wp-caption-text\"><em>Salinas romanas de Iptuci, en Prado del Rey (C\u00e1diz), Espa\u00f1a<\/em><\/p><\/div>\n<p>Xa desde outro punto de vista, o da <strong><em>riqueza extra\u00edda do mar<\/em><\/strong>, sen d\u00fabida hai que falar do sal. Mesmo durante o reinado de Anco Marcio unha porci\u00f3n da paga dos soldados era en sal; e precisamente de a\u00ed v\u00e9n o termo salario.<\/p>\n<p>Xa Plinio o Vello, afirmaba que <em>&#8220;non \u00e9 posible concibir unha vida civilizada sen a produci\u00f3n e o uso do sal&#8221;<\/em>, de feito a necesidade de sal foi desenvolvida a partir do Neol\u00edtico coa expansi\u00f3n da agricultura. A salgadura foi a t\u00e9cnica que adoptaron as poboaci\u00f3ns costeiras do Mediterr\u00e1neo para conservar durante moito tempo alimentos perecedoiros, como a carne e o peixe.<\/p>\n<p>Ademais, os romanos ti\u00f1an unha alta consideraci\u00f3n de todo o que era esencial para a vida, as\u00ed tanto o sal como a auga salgada ti\u00f1an un valor sacro e foi utilizada en ofrendas votivas aos deuses. O sal polas s\u00faas virtudes purificantes foi utilizada en sacrificios.<\/p>\n<p>&nbsp;<\/p>\n<p>E finalizamos esta aproximaci\u00f3n \u00e1 actividade no mar durante a \u00e9poca da antiga Roma, que esperamos resultouvos de interese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, berce dunha das grandes civilizaci\u00f3ns, fundouse nun lugar no que hab\u00eda outeiros e que facilitaba o seu defensa, ademais de que a trav\u00e9s do r\u00edo T\u00edber, pod\u00eda comunicarse co mar. Segundo a tradici\u00f3n Roma fundouse no ano 753 aC. por R\u00f3mulo e Remo; primeiro foi unha monarqu\u00eda etrusca, daquela (509 aC.) unha Rep\u00fablica e&hellip;<\/p>\n","protected":false},"author":2,"featured_media":7199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[65],"tags":[1161,271,1157,1160,1159,1162,237],"class_list":["post-7500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-gl","tag-a-mar","tag-curiosidades-historicas-gl","tag-flota-romana-gl","tag-o-mar","tag-ostia-gl","tag-roma-antiga","tag-sociedade","category-65","description-off"],"_links":{"self":[{"href":"https:\/\/recreacionhistoria.com\/gl\/wp-json\/wp\/v2\/posts\/7500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recreacionhistoria.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recreacionhistoria.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recreacionhistoria.com\/gl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/recreacionhistoria.com\/gl\/wp-json\/wp\/v2\/comments?post=7500"}],"version-history":[{"count":1,"href":"https:\/\/recreacionhistoria.com\/gl\/wp-json\/wp\/v2\/posts\/7500\/revisions"}],"predecessor-version":[{"id":7501,"href":"https:\/\/recreacionhistoria.com\/gl\/wp-json\/wp\/v2\/posts\/7500\/revisions\/7501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recreacionhistoria.com\/gl\/wp-json\/wp\/v2\/media\/7199"}],"wp:attachment":[{"href":"https:\/\/recreacionhistoria.com\/gl\/wp-json\/wp\/v2\/media?parent=7500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recreacionhistoria.com\/gl\/wp-json\/wp\/v2\/categories?post=7500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recreacionhistoria.com\/gl\/wp-json\/wp\/v2\/tags?post=7500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}